{"id":5625,"date":"2020-06-07T02:49:58","date_gmt":"2020-06-07T00:49:58","guid":{"rendered":"https:\/\/collectif-accad.fr\/site\/?p=5625"},"modified":"2020-06-05T17:52:32","modified_gmt":"2020-06-05T15:52:32","slug":"on-peut-et-on-doit-refuser-le-compteur-linky","status":"publish","type":"post","link":"https:\/\/collectif-accad.fr\/site\/on-peut-et-on-doit-refuser-le-compteur-linky\/","title":{"rendered":"On peut \u00a0et on doit refuser le compteur Linky\u00a0"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-size: 18pt;\"><strong>Attention aux mensonges et menaces d\u2019Enedis\u00a0!<\/strong><\/span><strong>\u00a0<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0Sur ce site, nous l\u2019avons d\u00e9j\u00e0 dit souvent. <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ce document qui suit est un rappel \u00e9crit sur\u00a0:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/refus.linky.gazpar.free.fr\">http:\/\/refus.linky.gazpar.free.fr<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Devrez-vous payer la rel\u00e8ve visuelle de votre consommation si<br \/>\nvous avez refus\u00e9 le Linky ?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Non, le linky n&rsquo;est pas obligatoire\u2026\u2026et il ne le sera pas plus en 2021<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Non, vous n\u2019aurez pas \u00e0 payer le compteur, ni une amende, ni avoir l\u2019\u00e9lectricit\u00e9 coup\u00e9e, etc<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Non, vous ne serez pas attaqu\u00e9 en justice \u00ab\u00a0sous 15 jours\u00a0\u00bb si vous barricadez votre compteur ordinaire pour le garder<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Harc\u00e8lement t\u00e9l\u00e9phonique ou physique\u00a0: d\u00e9fendez-vous\u00a0!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Dans la France enti\u00e8re,<strong> les citoyens sont de plus en plus nombreux \u00e0 refuser les compteurs communicants<\/strong>, \u00e0 commencer par le fameux Linky (compteur d\u2019\u00e9lectricit\u00e9). En particulier, plus de la moiti\u00e9 des compteurs d\u2019\u00e9lectricit\u00e9 du pays sont situ\u00e9s dans les logements et beaucoup de gens savent d\u00e9sormais qu\u2019<a href=\"http:\/\/refus.linky.gazpar.free.fr\/refus-individuels-ou-communes.htm\">ils sont alors en position de force\u00a0<\/a>: m\u00eame si vous n\u2019\u00eates que locataire, la Loi vous prot\u00e8ge, vous pouvez refuser l\u2019acc\u00e8s de votre logement aux installateurs.<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 cette situation qui leur \u00e9chappe, les dirigeants de l\u2019industriel Enedis (ex-ErDF, ex- service public) et ses sous-traitants (pay\u00e9s au nombre de compteurs pos\u00e9s) diffusent <strong>des rumeurs<\/strong>, y compris par courrier officiel, pour tenter d\u2019intimider les citoyens et les pousser \u00e0 ouvrir d\u2019eux-m\u00eames leur porte. Voici quelques exemples de ces mensonges et menaces\u00a0:<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; Devrez-vous payer la rel\u00e8ve visuelle de votre consommation si vous avez refus\u00e9 le Linky ?\u00a0: FAUX \u00e0 ce jour, et vous pouvez refuser Linky sans courir le moindre risque<\/strong><\/p>\n<p style=\"text-align: justify;\">Dans leurs courriers d&rsquo;intimidation, Enedis et ses sous-traitants voyous pr\u00e9tendent que les gens qui ont refus\u00e9 la Linky se verront appliquer \u00ab\u00a0<em>une facturation dont les modalit\u00e9s (prix notamment) sont en cours de d\u00e9finition par les autorit\u00e9s publiques<\/em>\u00a0\u00bb. Rien qu&rsquo;en lisant cette phrase, vous comprenez qu&rsquo;il n&rsquo;y a \u00e0 ce jour rien de concret : il s\u2019agit encore d&rsquo;une <strong>rumeur <\/strong>destin\u00e9e \u00e0 vous effrayer.<\/p>\n<p style=\"text-align: justify;\">Il est cependant exact qu&rsquo;Enedis, appuy\u00e9 par la CRE (*), esp\u00e8re la mise en place d&rsquo;une telle facturation (ce qui, notez-le au passage, est bien <strong>l&rsquo;aveu qu&rsquo;il est possible et l\u00e9gal de garder son compteur ordinaire !<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Si cette facturation, qui n&rsquo;existe absolument pas actuellement, est un jour mise en place, elle sera imm\u00e9diatement attaqu\u00e9e en justice pour plusieurs raisons\u00a0: la rel\u00e8ve de la consommation est d\u00e9j\u00e0 pay\u00e9e par une partie de nos factures d&rsquo;\u00e9lectricit\u00e9, or <strong>on ne peut pas facturer deux fois la m\u00eame chose<\/strong>. D&rsquo;autre part, il faudrait prouver qu&rsquo;un usager sans Linky co\u00fbte plus cher qu&rsquo;un usager \u00ab\u00a0linkys\u00e9\u00a0\u00bb, or c&rsquo;est probablement l&rsquo;inverse qui est vrai !<\/p>\n<p style=\"text-align: justify;\">Enfin, si vous vous inqui\u00e9tez d&rsquo;avoir peut-\u00eatre un jour \u00e0 payer une telle facturation, sachez <strong>qu&rsquo;Enedis ne pourra la mettre en place qu&rsquo;apr\u00e8s \u00ab\u00a0<em>plusieurs relances<\/em>\u00ab\u00a0<\/strong> (cf <a href=\"https:\/\/www.cre.fr\/Documents\/Deliberations\/Decision\/prestations-annexes9\/consulter-la-deliberation\">d\u00e9lib\u00e9ration du 3 mars 2016<\/a>, page 10) : Enedis devra vous proposer le Linky sans le moindre surco\u00fbt ni la moindre p\u00e9nalit\u00e9. Si le courage vous manque \u00e0 ce moment l\u00e0, vous pourrez toujours c\u00e9der, mais il est clair que pour le moment vous ne risquez strictement RIEN \u00e0 garder votre compteur ordinaire qui, faut-il le rappeler, est parfaitement l\u00e9gal (il a \u00e9t\u00e9 install\u00e9 par EDF ou ErDF ou Enedis selon les ann\u00e9es).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em>(*) La CRE est la \u00ab\u00a0Commission de r\u00e9gulation de l&rsquo;\u00e9nergie\u00a0\u00bb : une commission pr\u00e9tendue \u00ab\u00a0ind\u00e9pendante\u00a0\u00bb dont le r\u00f4le est avant tout d&rsquo;annoncer les mauvaises nouvelles, comme par exemple les augmentations du prix de l&rsquo;\u00e9nergie, \u00e0 la place du Gouvernement (qui se r\u00e9serve l&rsquo;annonce des bonnes nouvelles\u2026 quand il y en a). La CRE est une instance totalement antisociale compos\u00e9e de v\u00e9ritables parasites, tr\u00e8s grassement r\u00e9mun\u00e9r\u00e9s pour donner une apparente l\u00e9gitimit\u00e9 au racket de nos factures en faveur d&rsquo;Enedis et des fournisseurs d&rsquo;\u00e9lectricit\u00e9.<\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>&#8211; \u00ab<em>\u00a0La pose du Linky est obligatoire<\/em>\u00a0\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\">Enedis envoie des millions de lettres pr\u00e9tendant que le Linky est \u00ab\u00a0obligatoire\u00a0\u00bb, il s&rsquo;agit d&rsquo;un mensonge. Ce qu&rsquo;il faut bien comprendre, c&rsquo;est que la pose du Linky est l\u00e9gale (*)\u2026 mais que le fait de <strong>garder son compteur ordinaire est tout aussi l\u00e9gal !<\/strong> Votre compteur ordinaire a \u00e9t\u00e9 install\u00e9 par EDF, ou ErDF (puis Enedis), il est parfaitement valid\u00e9, vous ne pouvez pas \u00eatre \u00ab\u00a0hors la loi\u00a0\u00bb en le gardant ! Prenez donc toutes les mesures n\u00e9cessaires pour <strong><a href=\"http:\/\/refus.linky.gazpar.free.fr\/refus-linky-particuliers.htm\">emp\u00eacher mat\u00e9riellement la pose du Linky<\/a><\/strong>, et ne vous laissez pas intimider par les mensonges d&rsquo;Enedis et de ses sous-traitants voyous.<\/p>\n<p style=\"text-align: justify;\"><em>(*) du fait de la Loi de transition \u00e9nerg\u00e9tique : merci Hollande, Royal et Macron<\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>&#8211; \u00ab<em>\u00a0Inutile de r\u00e9sister car de toute fa\u00e7on vous aurez le Linky en 2021<\/em>\u00a0\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\">Le programme d&rsquo;installation des Linky doit effectivement s&rsquo;achever en 2021, mais ce n&rsquo;est pas pour autant que vous serez oblig\u00e9 de passer au Linky ! Comme expliqu\u00e9 ci-dessus, garder votre compteur ordinaire est parfaitement l\u00e9gal aujourd&rsquo;hui, et ce sera toujours le cas en 2021, en 2022, etc\u2026 Et avec un peu de chance, votre compteur durera encore des d\u00e9cennies (certains ont plus de 70 ans et tournent encore comme des horloges !). La seule inconnue est de savoir si vous devrez ou non payer une somme pour la rel\u00e8ve visuelle de votre consommation (cf ci-dessous).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>&#8211; \u00ab\u00a0<em>Si vous barricadez votre compteur ordinaire, vous serez attaqu\u00e9 en justice sous 15 jours<\/em>\u00a0\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\">Si votre compteur est accessible (par exemple s&rsquo;il donne sur la rue), la meilleure chance de le garder est de le barricader <a href=\"http:\/\/refus.linky.gazpar.free.fr\/compteurs-proteges.pdf\">comme le font de plus en plus de gens<\/a>. Si vous faites cela, vous recevez une lettre d&rsquo;Enedis pr\u00e9tendant que vous mettez le r\u00e9seau en danger (ce qui est stupide car 20 millions de compteurs sont dans les habitations, souvent dans des caves ou des garages : nous serions donc tous en grave danger !) et que, si vous n&rsquo;enlevez pas les protections sous 15 jours, vous serez poursuivi en justice.<\/p>\n<p style=\"text-align: justify;\">Or, au bout de 15 jours (et par la suite), il ne se passe strictement rien, tout simplement parce qu&rsquo;Enedis n&rsquo;est propri\u00e9taire ni du compteur (qui appartient aux collectivit\u00e9s territoriales) ni du coffret (qui vous appartient). Il s&rsquo;agit donc, encore une fois, d&rsquo;une minable tentative d&rsquo;intimidation.<\/p>\n<p style=\"text-align: justify;\">Notez aussi que les installateurs n&rsquo;ont <strong>pas le droit de briser vos protections. <a href=\"http:\/\/refus.linky.gazpar.free.fr\/jugement-la-rochelle.htm\">Voir le jugement \u00e9difiant du 20 juin 2017<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; \u00ab<em>\u00a0Si vous refusez le compteur Linky, vous allez payer une amende<\/em>\u00a0\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong>Les industriels avaient effectivement fait pression pour int\u00e9grer dans la Loi de transition \u00e9nerg\u00e9tique une amende de 1500 euros en cas de refus du Linky mais, de toute \u00e9vidence de peur de se mettre leurs \u00e9lecteurs \u00e0 dos, les parlementaires <strong>n\u2019ont pas vot\u00e9 cette disposition<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>&#8211; \u00ab\u00a0<em>Si vous refusez le compteur Linky aujourd\u2019hui alors qu\u2019il n\u2019est pas factur\u00e9, on vous l\u2019imposera plus tard et vous devrez alors le payer\u00a0<\/em>\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>La facturation d\u2019un compteur d\u2019\u00e9lectricit\u00e9 \u00e0 un particulier est tout simplement impossible<\/strong> car les compteurs (mais aussi la gestion et l\u2019entretien des lignes \u00e9lectriques et autres installations de distribution) sont pay\u00e9s par une partie de nos factures d\u2019\u00e9lectricit\u00e9 (environ 40% du montant), le TURPE\u00a0: Tarif d\u2019utilisation des r\u00e9seaux publics d\u2019\u00e9lectricit\u00e9. Cet argent n\u2019appartient pas \u00e0 Enedis, c\u2019est celui des citoyens, lesquels ne peuvent \u00eatre contraints de payer quelque chose qui est d\u00e9j\u00e0 pay\u00e9 par leurs factures.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a0<strong>&#8211; \u00ab\u00a0<em>Si vous refusez le compteur Linky, nous allons vous couper l\u2019\u00e9lectricit\u00e9<\/em>\u00a0\u00bb\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong>Les acquis sociaux sont peu \u00e0 peu remis en cause mais, \u00e0 ce jour, il reste heureusement encore extr\u00eamement complexe en France de couper l\u2019\u00e9lectricit\u00e9 \u00e0 des habitants. C\u2019est encore plus improbable, et ill\u00e9gal, si c\u2019est sous forme de r\u00e9torsion. Attention cependant\u00a0: pour intimider les citoyens, il arrive que les installateurs de Linky tentent de bidouiller votre syst\u00e8me \u00e9lectrique pour vous couper l\u2019\u00e9lectricit\u00e9, ou vous menacent de le faire. Si jamais cela vous arrivait, <strong>d\u00e9posez imm\u00e9diatement une plainte<\/strong> (au bureau de police ou \u00e0 la gendarmerie le plus proche), <strong>avertissez les m\u00e9dias locaux\u00a0<\/strong>: nous ne sommes pas encore en dictature et les milices d\u2019Enedis ne peuvent tout se permettre\u00a0! <strong>Exigez aussi l\u2019intervention de votre maire<\/strong>\u00a0: m\u00eame s\u2019il n\u2019a pas le courage de s\u2019opposer au d\u00e9ploiement des compteurs Linky, <strong>il se doit de prot\u00e9ger ses administr\u00e9s<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>&#8211; \u00ab\u00a0<em>Si vous avez des panneaux photovolta\u00efques, vous \u00eates oblig\u00e9 de prendre le Linky<\/em>\u00a0\u00bb (ou, variante, \u00ab\u00a0<em>un d\u00e9cret est en pr\u00e9paration pour vous y obliger<\/em>\u00a0\u00bb)\u00a0: FAUX<\/strong><\/p>\n<p style=\"text-align: justify;\">Vos contrats avec EDF ou un autre fournisseur sont en cours, en bonne et due forme, sans qu\u2019ils n\u2019\u00e9voquent de compteur Linky. Ces contrats ne peuvent \u00eatre modifi\u00e9s unilat\u00e9ralement. Attention donc si l\u2019on vous propose de signer un nouveau contrat \u00ab\u00a0mis \u00e0 jour\u00a0\u00bb\u00a0: cette mise \u00e0 jour concernera probablement Linky\u00a0!<strong> Ne signez rien, gardez vos contrats en cours<\/strong>\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a0<strong>ATTENTION\u00a0: HARC\u00c8LEMENT T\u00c9L\u00c9PHONIQUE VOIRE PHYSIQUE<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong>Pour tenter de faire craquer les citoyens lucides et courageux qui refusent les compteurs Linky, les installateurs s\u2019autorisent souvent \u00e0 les <strong>harceler<\/strong> par t\u00e9l\u00e9phone\u00a0: jusqu\u2019\u00e0 <strong>30 appels par jour<\/strong>\u00a0! Si cela vous arrive, <strong>notez soigneusement les jours, heures et minutes des appels<\/strong>, dites \u00e0 votre interlocuteur que vous allez porter plainte et, si le harc\u00e8lement continue, faites le r\u00e9ellement, au commissariat ou \u00e0 la gendarmerie, et \u00e9crivez au procureur de la R\u00e9publique\u00a0: <strong>ces m\u00e9thodes sont ill\u00e9gales et condamn\u00e9es par la loi<\/strong>. N\u2019h\u00e9sitez pas non plus \u00e0 appeler les m\u00e9dias locaux, mais l\u00e0 aussi \u00e0 <strong>exiger l\u2019intervention de votre maire<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Faites de m\u00eame si les gens d\u2019Enedis viennent chez vous, se montrent insistants, mena\u00e7ants, insultants. Filmez (ou faites filmer par un voisin) ces agissements indignes.<\/p>\n<p style=\"text-align: justify;\"><strong>CONCLUSION<\/strong><\/p>\n<p style=\"text-align: justify;\">En \u00e9voquant dans ses r\u00e9cents courriers \u00ab\u00a0la mise en place d&rsquo;une prestation r\u00e9siduelle de rel\u00e8ve \u00e0 pied, factur\u00e9e aux consommateurs qui ne seront pas \u00e9quip\u00e9s de compteurs \u00e9volu\u00e9s de leur fait, une fois leur zone de d\u00e9ploiement satur\u00e9e, et apr\u00e8s plusieurs relances\u00a0\u00bb, <strong>ENEDIS avoue que les refus sont tellement nombreux qu\u2019il faudra bien s\u2019y adapter de fa\u00e7on permanente<\/strong>. Continuons \u00e0 \u00eatre toujours plus nombreux \u00e0 refuser les compteurs communicants (Linky, Gazpar et cie), nous n\u2019aurons pas de \u00ab\u00a0prestation\u00a0\u00bb mensuelle \u00e0 payer ni d\u2019autres mesures de r\u00e9torsion, et nous prot\u00e8gerons nos libert\u00e9s et notre sant\u00e9.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Attention aux mensonges et menaces d\u2019Enedis\u00a0!\u00a0<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5625","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/posts\/5625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/comments?post=5625"}],"version-history":[{"count":1,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/posts\/5625\/revisions"}],"predecessor-version":[{"id":5626,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/posts\/5625\/revisions\/5626"}],"wp:attachment":[{"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/media?parent=5625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/categories?post=5625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/collectif-accad.fr\/site\/wp-json\/wp\/v2\/tags?post=5625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}